{"id":14544,"date":"2021-04-08T18:28:29","date_gmt":"2021-04-08T18:28:29","guid":{"rendered":"https:\/\/latribunera.com\/apuntes\/?p=14544"},"modified":"2021-04-08T18:28:35","modified_gmt":"2021-04-08T18:28:35","slug":"que-dijo-nahuel","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/04\/08\/que-dijo-nahuel\/","title":{"rendered":"\u00bfQU\u00c9 DIJO NAHUEL?"},"content":{"rendered":"<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:inline-block;width:728px;height:90px\"\ndata-ad-client=\"ca-pub-9427576701762839\"\ndata-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p>VENUSTIANO\nCARRANZA<\/p>\n\n\n\n<p>En la v\u00edspera de enfrentar al Am\u00e9rica, Nahuel Guzm\u00e1n, portero de Tigres, dio declaraciones a los medios de comunicaci\u00f3n; el Pat\u00f3n sin pelos en la lengua habl\u00f3 de todo un poco.<\/p>\n\n\n\n<p><strong>Am\u00e9rica, un equipo prolijo.<\/strong><\/p>\n\n\n\n<p>\u201c\u00daltimamente\nse nos est\u00e1n&nbsp;haciendo dif\u00edciles todos los partidos y hay que prepararse\npara cada uno de ellos al 100 por ciento como lo venimos haciendo, jugamos vs.\nel subl\u00edder, un equipo que ha sacado mucha ventaja en cuanto a la puntuaci\u00f3n,\nun equipo prolijo, compacto, vistoso, as\u00ed que esta semana trabajamos para\nenfrentar eso y contrarrestar los puntos altos<\/p>\n\n\n\n<p>\u201cHay que tratar\nde explotar nuestra idea en lo individual como en lo colectivo, si ser\u00e1 un\npartido duro, entiendo tambi\u00e9n que a diferencia de otros juegos tal vez Am\u00e9rica\nnos proponga un poco m\u00e1s en cuanto al juego, esto a lo mejor genere m\u00e1s\nespacios y haga un partido m\u00e1s entretenido a lo que a veces proponen otros\nequipos, as\u00ed que ojal\u00e1 sea un lindo espect\u00e1culo\u201d<\/p>\n\n\n\n<p>\u201cSobre la\nafici\u00f3n, yo por lo menos no tengo ninguna novedad, no s\u00e9 qu\u00e9&nbsp;pasar\u00e1 con\neso\u201d<\/p>\n\n\n\n<p><strong>Desmenuza las \u00c1guilas.<\/strong><\/p>\n\n\n\n<p>\u201cHoy\nAm\u00e9rica logr\u00f3 ser un equipo compacto, un equipo organizado, s\u00ed con ciertas individualidades,\npero en lo colectivo est\u00e1n haciendo y gran trabajo a la hora de la presi\u00f3n, estaba\nmirando algunas cosas y tiene una presi\u00f3n colectiva que viene de atr\u00e1s hacia\nadelante, y eso demuestra el sacrificio que est\u00e1n haciendo para con su equipo y\ncon su esquema.<\/p>\n\n\n\n<p>\u201cHablar de\nun jugador en particular no me gusta, si estar atentos porque manejan una buena\npelota parada, Richard S\u00e1nchez tiene tiro de buena distancia y delanteros\npotentes arriba, hoy el f\u00fatbol de Am\u00e9rica es en lo&nbsp;colectivo y si nosotros\nigualamos eso y lo superamos, por lo menos va a ser un partido entretenido y\nobviamente a veces destacan individualidades, pero hoy en d\u00eda este partido va a\nser orientado a lo colectivo, el que colectivamente haga bien las cosas tendr\u00e1\nm\u00e1s posibilidades\u201d<\/p>\n\n\n\n<p><strong>Conf\u00eda en Tigres<\/strong><\/p>\n\n\n\n<p>\u201cSi yo en lo personal o en lo colectivo sintiera que no tenemos posibilidades contra algunos de los equipos que enfrentamos durante el campeonato ni siquiera nos presentamos, entonces, justamente reci\u00e9n estaba diciendo que este es un partido que nos conviene hasta m\u00e1s que otros, porque son equipos que vienen a proponer\u00a0o que vienen con otra propuestas, ni m\u00e1s ni menos, vienen con otra propuesta de lo que vienen otros equipos, un poco m\u00e1s ofensivo, presi\u00f3n m\u00e1s alta, por momentos arriesgando o dejando manos a manos a la hora de presionar y eso tal vez nos de otro tipo de chances a lo que nos brindan otras propuestas de otros equipos, hasta siento que es un juego que nos conviene m\u00e1s y el conviene m\u00e1s al espect\u00e1culo. <\/p>\n\n\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:inline-block;width:728px;height:90px\"\ndata-ad-client=\"ca-pub-9427576701762839\"\ndata-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p>\u201cHay dos\nequipos que sacaron una gran diferencia en la tabla (Cruz Azul y Am\u00e9rica) y los\ndem\u00e1s estamos a seis puntos de diferencia lo que marca una paridad grande con\nel 80 por ciento del torneo de los equipos, as\u00ed que, es algo bueno lo que han\nlogrado esos dos equipos y todo lo dem\u00e1s estamos luchando para conseguir un\nequilibrio, eso respecto al juego contra Am\u00e9rica. Decirte que son partidos\nlindos no s\u00f3lo a nivel local sino a nivel nacional, en los \u00faltimos tiempos se\nhan hecho grandes encuentros y son de los partidos m\u00e1s entretenidos\nrecientemente\u201d<\/p>\n\n\n\n<p><strong>El regreso de la afici\u00f3n a los estadios<\/strong><\/p>\n\n\n\n<p>\u201cOjal\u00e1\npronto la podamos traer de vuelta con nosotros, para nosotros la afici\u00f3n nunca\nfue una olla de presi\u00f3n, siempre ha sido un impulso, ha empujado, alentando,\nhace siete a\u00f1os que estoy en este club y ya habido momentos especiales, muy\npuntuales.<\/p>\n\n\n\n<p>\u201cSiempre la\ngente ha tirado y empujado hacia adelante para acompa\u00f1ar lo que ha logrado este\nequipo a lo largo de este tiempo, ojal\u00e1 pronto podamos tener a la gente,\nentiendo que la gente tiene ganas de venir a la cancha, ve que en otros\nestadios las puertas ya se abrieron y eso a la gente le resuena, le molesta,\ntambi\u00e9n por el bien del f\u00fatbol, siendo conscientes de que hay que seguir\ncuid\u00e1ndose tanto&nbsp;dentro como fuera de la cancha, hay que mantener esta\ndisciplina con los cuidados personales y las que est\u00e1n cerca, no pasarlo por\nalto y respetar las normas\u201d<\/p>\n\n\n\n<p><strong>Sobre Santiago Solari, estratega del Am\u00e9rica<\/strong><\/p>\n\n\n\n<p>\u201cLos\nresultados dicen que no le da motivo de discusi\u00f3n, yo analizando un poco m\u00e1s\nque no va por el tema de los resultados note que con el tiempo ha logrado un\ncompromiso con su equipo e idea que se puede remarcar y se puede exponer en la\ncancha, eso va formando la identidad del equipo que \u00e9l quiere, entiendo que es\nuna persona muy formada, ha trabajado y jugado en uno de los mejores equipos\ndel mundo y hoy tiene la posibilidad de traer a M\u00e9xico&nbsp;estas experiencias,\nsu forma de ver el f\u00fatbol de jugarlo, entonces bienvenido este tipo de propuestas\ntambi\u00e9n, s\u00e9 que est\u00e1 acompa\u00f1ado por un gran cuerpo t\u00e9cnico, tengo la\nexperiencia de conocer personalmente al profe, entonces, nada m\u00e1s, esa es la\nmirada que tengo yo y si veo lo que se ve en el campo que ha logrado un\ncompromiso con su equipo que va mucho m\u00e1s all\u00e1 del resultado\u201d<\/p>\n\n\n\n<p><strong>No quiere controversias <\/strong><\/p>\n\n\n\n<p>\u201cSi digo\nque estamos en deuda o no, las dos respuestas pueden generar controversia, o\nustedes dudan de lo que digo o la gente se enoja, hablar de si estamos en deuda\nme parece reducir a muy poquito lo que el equipo est\u00e1 haciendo.<\/p>\n\n\n\n<p>\u201cNos vino muy bien esa victoria (ante Gallos) fue positiva para el trabajo en la semana, la confianza en el equipo, no ganamos como nos hubiese gustado, as\u00ed como otros partidos hemos hecho las cosas muy bien y nos hemos quedado con las manos vac\u00edas. A veces prefiero ganar y estamos en un momento que era salir a ganar y ahora podemos preparar nuevamente otro partido de la manera que, de salir con la victoria en el bolsillo, y eso conscientemente da otro tipo de confianza en lo individual y en lo colectivo\u201d<\/p>\n\n\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:inline-block;width:728px;height:90px\"\ndata-ad-client=\"ca-pub-9427576701762839\"\ndata-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Tigres vs Am\u00e9rica. Jornada 14. Guardianes 2021\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/x-krUwoc8V8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n","protected":false},"excerpt":{"rendered":"<p>VENUSTIANO CARRANZA En la v\u00edspera de enfrentar al Am\u00e9rica, Nahuel Guzm\u00e1n, portero de Tigres, dio declaraciones a los medios de comunicaci\u00f3n; el Pat\u00f3n sin pelos en la lengua habl\u00f3 de todo un poco. Am\u00e9rica, un equipo prolijo. \u201c\u00daltimamente se nos est\u00e1n&nbsp;haciendo dif\u00edciles todos los partidos y hay que prepararse para cada uno de ellos al&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/04\/08\/que-dijo-nahuel\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":26,"featured_media":14545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[231,3,2,278],"tags":[85,174,74,102],"class_list":["post-14544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apuntes","category-futbol","category-futbol-mexicano","category-solotigres","tag-america","tag-covid19","tag-liga-mx","tag-tigres"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2021\/04\/image11100001.jpeg","jetpack-related-posts":[{"id":45386,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/03\/11\/santos-launa-impulsa-mejoras-en-la-infraestructura-de-tsm-y-estadio-corona\/","url_meta":{"origin":14544,"position":0},"title":"Santos Laguna impulsa mejoras en la infraestructura de TSM y Estadio Corona","author":"Jacob Alarcon","date":"11 marzo, 2026","format":false,"excerpt":"Club Santos Laguna lleva a cabo una serie de reformas y mejoras en la infraestructura de TerritorioSantos Modelo y del Estadio Corona, con el objetivo de impulsar la innovaci\u00f3n tecnol\u00f3gica, lasostenibilidad y la modernizaci\u00f3n de sus espacios.Con estas acciones, el club contin\u00faa fortaleciendo la experiencia de sus aficionados yactualizando sus\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45421,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/16\/todo-listo-para-la-14va-edicion-de-la-copa-internacional-santos-penoles\/","url_meta":{"origin":14544,"position":1},"title":"Todo listo para la 14va edici\u00f3n de la Copa Internacional Santos Pe\u00f1oles","author":"Jacob Alarcon","date":"16 abril, 2026","format":false,"excerpt":"Este jueves, en el Auditorio Orlegi de Territorio Santos Modelo, se llev\u00f3 a cabo la presentaci\u00f3noficial de la edici\u00f3n 2026 de la Copa Internacional Santos Pe\u00f1oles, torneo que se ha consolidadocomo uno de los m\u00e1s importantes a nivel infantil y juvenil en M\u00e9xico. Adem\u00e1s de brindar una competencia deportiva de\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45392,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/09\/se-presento-la-13va-edicion-del-guerreton\/","url_meta":{"origin":14544,"position":2},"title":"Se presento la 13va edici\u00f3n del Guerret\u00f3n.","author":"Staff","date":"9 abril, 2026","format":false,"excerpt":"A lo largo de sus primeras 12 ediciones, Guerret\u00f3n ha logrado recolectar m\u00e1s de 121,500juguetes, peluches y balones, beneficiando a diversas asociaciones e instituciones de laregi\u00f3n lagunera, entre ellas CRIT Durango, los sistemas DIF de distintos municipios, as\u00edcomo organizaciones educativas y asistenciales. A la fecha, se han instalado cuatro ludotecas\u2026","rel":"","context":"In &quot;Ganar Sirviendo&quot;","block_context":{"text":"Ganar Sirviendo","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/futbol\/futbol-mexicano\/ganar-sirviendo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/14544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=14544"}],"version-history":[{"count":2,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/14544\/revisions"}],"predecessor-version":[{"id":14548,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/14544\/revisions\/14548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/14545"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=14544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=14544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=14544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}