{"id":15001,"date":"2021-04-16T21:21:01","date_gmt":"2021-04-16T21:21:01","guid":{"rendered":"https:\/\/latribunera.com\/apuntes\/?p=15001"},"modified":"2021-04-16T21:55:22","modified_gmt":"2021-04-16T21:55:22","slug":"rayos-no-gallos","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/04\/16\/rayos-no-gallos\/","title":{"rendered":"Rayos no Gallos"},"content":{"rendered":"<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><strong>Por Blanca Mendoza \/  @BlanchLady <\/strong><\/p>\n\n\n\n<p>A los Rayos le quedan 2\npartidos de local; Quer\u00e9taro partido de hoy en la noche y Atlas en la \u00faltima\njornada, creo que debe aprovechar el aliento de su afici\u00f3n como motivaci\u00f3n de\nesfuerzo para cerrar dignamente en el Victoria, en estos dos juegos,\nprincipalmente.<\/p>\n\n\n\n<p>Estad\u00edsticamente Necaxa es\nmuy superior a Quer\u00e9taro, desde que los Rayos regresaron a Primera Divisi\u00f3n, 7\ntriunfos para Necaxa, un empate y 3 triunfos para Quer\u00e9taro, pero, la mala\nnoticia es que los Rayos le ha ganado m\u00e1s a los Gallos en la Corregidora, que\nen el Victoria. <\/p>\n\n\n\n<p>Aun as\u00ed, las cifras son esperanzadoras para nosotros, aunque si hay que recalcar que Quer\u00e9taro esta buscando afianzarse en la Repesca y hasta puede calificar a la Liguilla directo, todo pinta para que sea un Gallo inc\u00f3modo.<\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p>A Guillermo V\u00e1zquez le va bien jugando en contra de los Gallos, recordemos aquellos Cuartos De final, \u00e9picos de la mano de \u201cMemo\u201d, donde Necaxa fue contundente en el Victoria con un 3-0 y en la Corregidora, los Rayos remontaron y se les gan\u00f3 con un 2-3. <\/p>\n\n\n\n<p>Necaxa, bajo el mando de\n\u201cMemo\u201d V\u00e1zquez, se le ha visto algunas mejoras en su funcionar, pero sabemos lo\nlimitado que es el plantel, por eso espero y deseo que el equipo pueda cerrar lo\nmejor que se pueda en estos tres \u00faltimos partidos, para darle la vuela a la\npagina lo m\u00e1s decoroso y empezar a escribir un nuevo proyecto que como sabemos,\nen el papel luce bien, rumbo al centenario.<\/p>\n\n\n\n<p>\u00a1Fuerza Rayos!<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Necaxa vs Quer\u00e9taro. Jornada 15. Guardianes 2021\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/8PwpVVrWcZI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><strong>CARICATURA: @murdokheras<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Blanca Mendoza \/ @BlanchLady A los Rayos le quedan 2 partidos de local; Quer\u00e9taro partido de hoy en la noche y Atlas en la \u00faltima jornada, creo que debe aprovechar el aliento de su afici\u00f3n como motivaci\u00f3n de esfuerzo para cerrar dignamente en el Victoria, en estos dos juegos, principalmente. Estad\u00edsticamente Necaxa es muy&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/04\/16\/rayos-no-gallos\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":8,"featured_media":15002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[231,3,2],"tags":[115,114,252],"class_list":["post-15001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apuntes","category-futbol","category-futbol-mexicano","tag-necaxa","tag-queretaro","tag-rayos"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2021\/04\/Dise\u00f1o-sin-t\u00edtulo-1-6.jpg","jetpack-related-posts":[{"id":45392,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/09\/se-presento-la-13va-edicion-del-guerreton\/","url_meta":{"origin":15001,"position":0},"title":"Se presento la 13va edici\u00f3n del Guerret\u00f3n.","author":"Staff","date":"9 abril, 2026","format":false,"excerpt":"A lo largo de sus primeras 12 ediciones, Guerret\u00f3n ha logrado recolectar m\u00e1s de 121,500juguetes, peluches y balones, beneficiando a diversas asociaciones e instituciones de laregi\u00f3n lagunera, entre ellas CRIT Durango, los sistemas DIF de distintos municipios, as\u00edcomo organizaciones educativas y asistenciales. A la fecha, se han instalado cuatro ludotecas\u2026","rel":"","context":"In &quot;Ganar Sirviendo&quot;","block_context":{"text":"Ganar Sirviendo","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/futbol\/futbol-mexicano\/ganar-sirviendo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45386,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/03\/11\/santos-launa-impulsa-mejoras-en-la-infraestructura-de-tsm-y-estadio-corona\/","url_meta":{"origin":15001,"position":1},"title":"Santos Laguna impulsa mejoras en la infraestructura de TSM y Estadio Corona","author":"Jacob Alarcon","date":"11 marzo, 2026","format":false,"excerpt":"Club Santos Laguna lleva a cabo una serie de reformas y mejoras en la infraestructura de TerritorioSantos Modelo y del Estadio Corona, con el objetivo de impulsar la innovaci\u00f3n tecnol\u00f3gica, lasostenibilidad y la modernizaci\u00f3n de sus espacios.Con estas acciones, el club contin\u00faa fortaleciendo la experiencia de sus aficionados yactualizando sus\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45444,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/06\/23\/estadio-corona-y-tsm-inversion-y-evolucion-en-su-infraestructura\/","url_meta":{"origin":15001,"position":2},"title":"ESTADIO CORONA Y TSM: INVERSI\u00d3N Y EVOLUCI\u00d3N EN SU INFRAESTRUCTURA","author":"Jacob Alarcon","date":"23 junio, 2026","format":false,"excerpt":"El Estadio Corona y Territorio Santos Modelo contin\u00faan evolucionando con una serie de mejoras enfocadas en innovaci\u00f3n, tecnolog\u00eda, sostenibilidad y una experiencia integral para aficionados, jugadores, aliados comerciales y visitantes en general. Se realiza una inversi\u00f3n importante en infraestructura y, particularmente durante los \u00faltimos ocho meses, se han concretado obras\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":45450,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/07\/02\/santos-laguna-recibira-america-de-cali-historico-del-futbol-sudamericano-en-el-estadio-corona\/","url_meta":{"origin":15001,"position":3},"title":"Santos Laguna recibir\u00e1 Am\u00e9rica de Cali hist\u00f3rico del futbol sudamericano, en el Estadio Corona.","author":"Jacob Alarcon","date":"2 julio, 2026","format":false,"excerpt":"El encuentro se disputar\u00e1 el jueves 9 de julio y representar\u00e1 el regreso de un partido de preparaci\u00f3n ante un rival internacional en el Estadio Corona, previo al inicio del Torneo Apertura 2026. \u2022 Los boletos estar\u00e1n disponibles en $100 y $150 pesos. \u2022 Los Abonados Guerrero Total ingresar\u00e1n sin\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45421,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/16\/todo-listo-para-la-14va-edicion-de-la-copa-internacional-santos-penoles\/","url_meta":{"origin":15001,"position":4},"title":"Todo listo para la 14va edici\u00f3n de la Copa Internacional Santos Pe\u00f1oles","author":"Jacob Alarcon","date":"16 abril, 2026","format":false,"excerpt":"Este jueves, en el Auditorio Orlegi de Territorio Santos Modelo, se llev\u00f3 a cabo la presentaci\u00f3noficial de la edici\u00f3n 2026 de la Copa Internacional Santos Pe\u00f1oles, torneo que se ha consolidadocomo uno de los m\u00e1s importantes a nivel infantil y juvenil en M\u00e9xico. Adem\u00e1s de brindar una competencia deportiva de\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45434,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/05\/28\/45434\/","url_meta":{"origin":15001,"position":5},"title":"Renato Paiva es presentado como Director T\u00e9cnico de Santos Laguna","author":"Jacob Alarcon","date":"28 mayo, 2026","format":false,"excerpt":"Santos Laguna llev\u00f3 a cabo este jueves la presentaci\u00f3n oficial de Renato Paiva como nuevo Director T\u00e9cnico del Primer Equipo, en conferencia de prensa realizada en el Auditorio Orlegi de Territorio Santos Modelo, encabezada por Alejandro Irarragorri Kalb, Presidente del Club, y Gonzalo Pineda, Director de Futbol del Primer Equipo.\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/15001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=15001"}],"version-history":[{"count":3,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/15001\/revisions"}],"predecessor-version":[{"id":15005,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/15001\/revisions\/15005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/15002"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=15001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=15001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=15001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}