{"id":17490,"date":"2021-06-05T01:08:09","date_gmt":"2021-06-05T01:08:09","guid":{"rendered":"https:\/\/latribunera.com\/apuntes\/?p=17490"},"modified":"2021-06-05T01:12:42","modified_gmt":"2021-06-05T01:12:42","slug":"volpi-y-el-dia-que-estuvo-cerca-del-madrid","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/06\/05\/volpi-y-el-dia-que-estuvo-cerca-del-madrid\/","title":{"rendered":"VOLPI Y EL D\u00cdA QUE ESTUVO CERCA DEL MADRID"},"content":{"rendered":"<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p>Por Diego de Montemayor <\/p>\n\n\n\n<p>Esta buena\nla disputa por el arco de Rayados: por un lado, el argentino de Boca, Esteban\nAndrada; por el otro el brasile\u00f1o Tiago Volpi que ya conoce la Liga MX.<\/p>\n\n\n\n<p>Sea Volpi o\nAndrada es un hecho que la directiva de Rayados est\u00e1 enmendando un error\nincre\u00edble, dense cuenta de la tremenda diferencia entre Hugo Gonz\u00e1lez y los dos\narqueros de origen extranjero.<\/p>\n\n\n\n<p>Viendo los videos de Andrada y Volpi -obviamente como sus jugadas m\u00e1s vistosas- podemos analizar una serie de atajadas que nunca le vimos a Hugo en dos etapas. Solo para que se den una idea.<\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p>\u00bfQui\u00e9n es\nmejor? \u00bfAndrada o Volpi? Pues la respuesta es que en gustos se rompen g\u00e9neros,\nel brasile\u00f1o tendr\u00eda un punto a favor por conocer la Liga MX por su paso por\nQuer\u00e9taro.<\/p>\n\n\n\n<p>Por cierto,\nmientras Volpi defend\u00eda los tres palos blancos de los Gallos hubo una noticia\nque estremeci\u00f3 el mercado mexicano y eso fue que vinieron de Europa a buscar al\nbrasile\u00f1o.<\/p>\n\n\n\n<p>Cuenta la\nleyenda que gente del Real Madrid habr\u00eda tenido contacto con los directivos del\nQuer\u00e9taro para fichar a Tiago, algo que finamente no se dio.<\/p>\n\n\n\n<p>Todo esto ocurri\u00f3 durante el 2016 cuando los merengues por poco se llevan al que podr\u00eda ser el pr\u00f3ximo arquero del Monterrey.<\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Por Diego de Montemayor Esta buena la disputa por el arco de Rayados: por un lado, el argentino de Boca, Esteban Andrada; por el otro el brasile\u00f1o Tiago Volpi que ya conoce la Liga MX. Sea Volpi o Andrada es un hecho que la directiva de Rayados est\u00e1 enmendando un error incre\u00edble, dense cuenta de&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/06\/05\/volpi-y-el-dia-que-estuvo-cerca-del-madrid\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":13,"featured_media":17494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[231,3,2,277],"tags":[74],"class_list":["post-17490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apuntes","category-futbol","category-futbol-mexicano","category-zonarayada","tag-liga-mx"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2021\/06\/Dise\u00f1o-sin-t\u00edtulo-1-4.jpg","jetpack-related-posts":[{"id":45392,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/09\/se-presento-la-13va-edicion-del-guerreton\/","url_meta":{"origin":17490,"position":0},"title":"Se presento la 13va edici\u00f3n del Guerret\u00f3n.","author":"Staff","date":"9 abril, 2026","format":false,"excerpt":"A lo largo de sus primeras 12 ediciones, Guerret\u00f3n ha logrado recolectar m\u00e1s de 121,500juguetes, peluches y balones, beneficiando a diversas asociaciones e instituciones de laregi\u00f3n lagunera, entre ellas CRIT Durango, los sistemas DIF de distintos municipios, as\u00edcomo organizaciones educativas y asistenciales. A la fecha, se han instalado cuatro ludotecas\u2026","rel":"","context":"In &quot;Ganar Sirviendo&quot;","block_context":{"text":"Ganar Sirviendo","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/futbol\/futbol-mexicano\/ganar-sirviendo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/17490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=17490"}],"version-history":[{"count":3,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/17490\/revisions"}],"predecessor-version":[{"id":17495,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/17490\/revisions\/17495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/17494"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=17490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=17490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=17490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}