{"id":18625,"date":"2021-06-28T13:17:48","date_gmt":"2021-06-28T13:17:48","guid":{"rendered":"https:\/\/latribunera.com\/apuntes\/?p=18625"},"modified":"2021-06-28T13:28:22","modified_gmt":"2021-06-28T13:28:22","slug":"mauricio-doehner-y-su-vision-mas-alla-del-balon","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/06\/28\/mauricio-doehner-y-su-vision-mas-alla-del-balon\/","title":{"rendered":"Mauricio Doehner y su visi\u00f3n m\u00e1s all\u00e1 del bal\u00f3n"},"content":{"rendered":"\n<p><\/p>\n\n\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:inline-block;width:728px;height:90px\"\ndata-ad-client=\"ca-pub-9427576701762839\"\ndata-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Lo que Mauricio Doehner pretende lograr con Tigres, va m\u00e1s all\u00e1 de lo que se haga o deje de hacer con el bal\u00f3n; de los triunfos de temporada regular y de las victorias que le permiten al equipo dar la vuelta ol\u00edmpica y bordarse una estrella en el escudo.<\/p>\n\n\n\n<p>El hombre entiende que Tigres es m\u00e1s que un simple club de f\u00fatbol. Sabe, mejor dicho, que el f\u00fatbol, en Nuevo Le\u00f3n, ha dejado de ser ese deporte en el que la competencia se limita a meter m\u00e1s goles que el rival y recibir los menos.&nbsp;<\/p>\n\n\n\n<p>El juego se ha convertido en una industria de dimensiones colosales, dentro de la cual importa todo.<\/p>\n\n\n\n<p>No basta con armar un equipo ganador; Tigres debe demostrar, fuera y dentro de la cancha, la grandeza de la empresa que los representa, y dicha grandeza precisa de los mejores jugadores y del mejor entrenador; de las mejores instalaciones y de aspirar siempre a la gloria; yendo un paso por delante del resto de los competidores.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"NUEVO ESTADIO DE TIGRES - Mauricio Doehner\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/LwmpHGU-MxY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:inline-block;width:728px;height:90px\"\ndata-ad-client=\"ca-pub-9427576701762839\"\ndata-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En el camino, sin embargo, Mauricio Doehner se encontrar\u00e1 con el escepticismo y la reprobaci\u00f3n de aquellos hinchas que permanecen renuentes al cambio. Que creen que el \u00fanico camino para llegar al \u00e9xito fue el tomado en la d\u00e9cada pasada, y por ende, toda propuesta la reciben como una amenaza.<\/p>\n\n\n\n<p>Por lo pronto, Mauricio renunci\u00f3 al confort y le dio las gracias a uno de los pocos entrenadores en el f\u00fatbol mexicano (quiz\u00e1s el \u00fanico) que te garantiza cierta estabilidad t\u00e1ctica y competitiva, para firmar a un director t\u00e9cnico atrevido y con hambre de siempre lograr un poquito m\u00e1s de lo presupuestado, asumiendo los riesgos a los cuales se pueda enfrentar.<\/p>\n\n\n\n<p>Muchos se burlaron cuando Mauricio pens\u00f3 en fichar a Florian Thauvin. Lo tacharon de loco pues lo estimaban imposible; hoy el franc\u00e9s ya entrena con Tigres.<\/p>\n\n\n\n<p>Propuso una suerte de orden de compra para futuras contrataciones, a trav\u00e9s de la cual el entrenador deber\u00e1 argumentar por qu\u00e9 quiere contratar a determinado jugador, esto con el fin de cuidar a los activos del equipo y as\u00ed evitar que se deval\u00faen en la banca por temas que no tengan nada que ver con lo futbol\u00edstico.<\/p>\n\n\n\n<p>Puso sobre la mesa la remodelaci\u00f3n\/construcci\u00f3n del estadio; se plante\u00f3 por vez primera dejar Zuazua, pensando en el bienestar de los jugadores y su correcto descanso.<\/p>\n\n\n\n<p>Y todo esto antes de que comience a rodar la pelota\u2026<\/p>\n\n\n\n<p>Podr\u00e1 gustar o no, pero es un hecho que Tigres tiene como l\u00edder a un hombre innovador.<\/p>\n\n\n\n<p>Tambi\u00e9n te puede interesar:<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/06\/25\/como-debe-jugar-tigres-sin-sus-seleccionados\/\">\u00bfC\u00f3mo debe jugar Tigres sin sus seleccionados?<\/a><\/strong><\/p>\n\n\n\n<p>Twitter:&nbsp;<strong><a href=\"http:\/\/www.twitter.com\/JaimeGarza94\">JaimeGarza94<\/a><\/strong><\/p>\n\n\n\n<p>Instagram:\u00a0<strong><a href=\"http:\/\/www.instagram.com\/JaimeGarzaAutor\">JaimeGarzaAutor<\/a><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:inline-block;width:728px;height:90px\"\ndata-ad-client=\"ca-pub-9427576701762839\"\ndata-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"TIGRES NO TOMA DECISIONES POR OCURRENCIAS - Mauricio Doehner\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/pgqa86bedgw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Lo que Mauricio Doehner pretende lograr con Tigres, va m\u00e1s all\u00e1 de lo que se haga o deje de hacer con el bal\u00f3n; de los triunfos de temporada regular y de las victorias que le permiten al equipo dar la vuelta ol\u00edmpica y bordarse una estrella en el escudo. El hombre entiende que Tigres es&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/06\/28\/mauricio-doehner-y-su-vision-mas-alla-del-balon\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":23,"featured_media":18626,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[278],"tags":[452,102],"class_list":["post-18625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solotigres","tag-mauricio-doehner","tag-tigres"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2021\/06\/doehner.jpg","jetpack-related-posts":[{"id":45392,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/09\/se-presento-la-13va-edicion-del-guerreton\/","url_meta":{"origin":18625,"position":0},"title":"Se presento la 13va edici\u00f3n del Guerret\u00f3n.","author":"Staff","date":"9 abril, 2026","format":false,"excerpt":"A lo largo de sus primeras 12 ediciones, Guerret\u00f3n ha logrado recolectar m\u00e1s de 121,500juguetes, peluches y balones, beneficiando a diversas asociaciones e instituciones de laregi\u00f3n lagunera, entre ellas CRIT Durango, los sistemas DIF de distintos municipios, as\u00edcomo organizaciones educativas y asistenciales. A la fecha, se han instalado cuatro ludotecas\u2026","rel":"","context":"In &quot;Ganar Sirviendo&quot;","block_context":{"text":"Ganar Sirviendo","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/futbol\/futbol-mexicano\/ganar-sirviendo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45450,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/07\/02\/santos-laguna-recibira-america-de-cali-historico-del-futbol-sudamericano-en-el-estadio-corona\/","url_meta":{"origin":18625,"position":1},"title":"Santos Laguna recibir\u00e1 Am\u00e9rica de Cali hist\u00f3rico del futbol sudamericano, en el Estadio Corona.","author":"Jacob Alarcon","date":"2 julio, 2026","format":false,"excerpt":"El encuentro se disputar\u00e1 el jueves 9 de julio y representar\u00e1 el regreso de un partido de preparaci\u00f3n ante un rival internacional en el Estadio Corona, previo al inicio del Torneo Apertura 2026. \u2022 Los boletos estar\u00e1n disponibles en $100 y $150 pesos. \u2022 Los Abonados Guerrero Total ingresar\u00e1n sin\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/Santos-vs-America-de-Cali.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45434,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/05\/28\/45434\/","url_meta":{"origin":18625,"position":2},"title":"Renato Paiva es presentado como Director T\u00e9cnico de Santos Laguna","author":"Jacob Alarcon","date":"28 mayo, 2026","format":false,"excerpt":"Santos Laguna llev\u00f3 a cabo este jueves la presentaci\u00f3n oficial de Renato Paiva como nuevo Director T\u00e9cnico del Primer Equipo, en conferencia de prensa realizada en el Auditorio Orlegi de Territorio Santos Modelo, encabezada por Alejandro Irarragorri Kalb, Presidente del Club, y Gonzalo Pineda, Director de Futbol del Primer Equipo.\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/RENATO-PAIVA.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45429,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/05\/19\/club-santos-laguna-anuncia-a-renato-paiva-como-director-tecnico-de-los-guerreros\/","url_meta":{"origin":18625,"position":3},"title":"Club Santos Laguna anuncia a Renato Paiva como director t\u00e9cnico de los Guerreros","author":"Jacob Alarcon","date":"19 mayo, 2026","format":false,"excerpt":"Club Santos Laguna informa la contrataci\u00f3n de Renato Manuel Alves Paiva como Director T\u00e9cnico del Primer Equipo de los Guerreros. La incorporaci\u00f3n del estratega portugu\u00e9s forma parte de la reestructura deportiva que vive la instituci\u00f3n santista, enfocada en impulsar un cambio de fondo que permita fortalecer su metodolog\u00eda de trabajo\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/b5856b03-d2a7-4e72-95af-09fe86011ed5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/b5856b03-d2a7-4e72-95af-09fe86011ed5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/b5856b03-d2a7-4e72-95af-09fe86011ed5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/b5856b03-d2a7-4e72-95af-09fe86011ed5.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/b5856b03-d2a7-4e72-95af-09fe86011ed5.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/05\/b5856b03-d2a7-4e72-95af-09fe86011ed5.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45386,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/03\/11\/santos-launa-impulsa-mejoras-en-la-infraestructura-de-tsm-y-estadio-corona\/","url_meta":{"origin":18625,"position":4},"title":"Santos Laguna impulsa mejoras en la infraestructura de TSM y Estadio Corona","author":"Jacob Alarcon","date":"11 marzo, 2026","format":false,"excerpt":"Club Santos Laguna lleva a cabo una serie de reformas y mejoras en la infraestructura de TerritorioSantos Modelo y del Estadio Corona, con el objetivo de impulsar la innovaci\u00f3n tecnol\u00f3gica, lasostenibilidad y la modernizaci\u00f3n de sus espacios.Con estas acciones, el club contin\u00faa fortaleciendo la experiencia de sus aficionados yactualizando sus\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45444,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/06\/23\/estadio-corona-y-tsm-inversion-y-evolucion-en-su-infraestructura\/","url_meta":{"origin":18625,"position":5},"title":"ESTADIO CORONA Y TSM: INVERSI\u00d3N Y EVOLUCI\u00d3N EN SU INFRAESTRUCTURA","author":"Jacob Alarcon","date":"23 junio, 2026","format":false,"excerpt":"El Estadio Corona y Territorio Santos Modelo contin\u00faan evolucionando con una serie de mejoras enfocadas en innovaci\u00f3n, tecnolog\u00eda, sostenibilidad y una experiencia integral para aficionados, jugadores, aliados comerciales y visitantes en general. Se realiza una inversi\u00f3n importante en infraestructura y, particularmente durante los \u00faltimos ocho meses, se han concretado obras\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/18625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=18625"}],"version-history":[{"count":4,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/18625\/revisions"}],"predecessor-version":[{"id":18630,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/18625\/revisions\/18630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/18626"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=18625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=18625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=18625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}