{"id":23672,"date":"2021-10-11T22:47:44","date_gmt":"2021-10-11T22:47:44","guid":{"rendered":"https:\/\/latribunera.com\/apuntes\/?p=23672"},"modified":"2021-10-11T22:48:39","modified_gmt":"2021-10-11T22:48:39","slug":"juan-pablo-vigon-el-arte-del-mediocentro-box-to-box","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/10\/11\/juan-pablo-vigon-el-arte-del-mediocentro-box-to-box\/","title":{"rendered":"Juan Pablo Vig\u00f3n: el arte del mediocentro &#8216;box to box&#8217;"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:inline-block;width:728px;height:90px\"\ndata-ad-client=\"ca-pub-9427576701762839\"\ndata-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En medio de la explosi\u00f3n medi\u00e1tica que caus\u00f3 la contrataci\u00f3n del franc\u00e9s Florian Thauvin, el equipo de Miguel Herrera cerr\u00f3 un fichaje que lleg\u00f3 sin reflectores y junto a sus grandes actuaciones comenz\u00f3 a brillar con la camiseta auriazul.<\/p>\n\n\n\n<p>Juan Pablo Vig\u00f3n, procedente de Pumas, se uni\u00f3 a las filas de Tigres con un perfil de jugador conocido por la afici\u00f3n, pero que hace rato no ten\u00eda un papel protag\u00f3nico en el equipo, ese jugador todoterreno capaz de desempe\u00f1arse en cualquier posici\u00f3n y con una garra que combina a la perfecci\u00f3n en esta instituci\u00f3n.<\/p>\n\n\n\n<p>Vig\u00f3n es la representaci\u00f3n del medio campista conocido como &#8216;box to box&#8217;, pisa las dos \u00e1reas con la misma eficacia y aparece por todo el terreno de juego, es un jugador que no es malo en ning\u00fan aspecto porque tiene un poco de cada habilidad, as\u00ed como sus picos altos en aspectos como recuperaci\u00f3n y llegada al \u00e1rea rival.<\/p>\n\n\n\n<p>Pese a llegar a un plantel repleto de calidad y pelear un puesto contra jugadores del nivel de Guido Pizarro y Rafael Carioca, Vig\u00f3n se hizo un hueco desde sus primeros partidos, y actualmente ya sea partiendo de inicio o saliendo desde el banquillo, su presencia suele ser un diferenciador para el nivel de Tigres.<\/p>\n\n\n\n<p>Para dar una muestra en n\u00fameros, el motor felino tiene 12 partidos con la camiseta auriazul, en ataque suma 13 tiros de los cuales siete han ido a puerta, ha ganado el 41% de sus duelos y tiene 55 recuperaciones, ha hecho 15 faltas y le han hecho 16, y un total de 352 pases con un porcentaje de acierto del 87%.<\/p>\n\n\n\n<p>&#8216;Juanpi&#8217; es uno de esos jugadores que no sab\u00edamos que necesit\u00e1bamos y ahora le queremos siempre, un comod\u00edn para el plantel de Miguel Herrera que aporta en todas las facetas del juego, que aument\u00f3 la competencia y que con sus actuaciones se va ganando el cari\u00f1o de la afici\u00f3n incomparable.<\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:inline-block;width:728px;height:90px\"\ndata-ad-client=\"ca-pub-9427576701762839\"\ndata-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:inline-block;width:728px;height:90px\"\ndata-ad-client=\"ca-pub-9427576701762839\"\ndata-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio de la explosi\u00f3n medi\u00e1tica que caus\u00f3 la contrataci\u00f3n del franc\u00e9s Florian Thauvin, el equipo de Miguel Herrera cerr\u00f3 un fichaje que lleg\u00f3 sin reflectores y junto a sus grandes actuaciones comenz\u00f3 a brillar con la camiseta auriazul. Juan Pablo Vig\u00f3n, procedente de Pumas, se uni\u00f3 a las filas de Tigres con un perfil&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2021\/10\/11\/juan-pablo-vigon-el-arte-del-mediocentro-box-to-box\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":37,"featured_media":23679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,278],"tags":[102],"class_list":["post-23672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-mexicano","category-solotigres","tag-tigres"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2021\/10\/FBI6RAUYMJHY3NXIQBKMR7YDVI.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/23672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=23672"}],"version-history":[{"count":4,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/23672\/revisions"}],"predecessor-version":[{"id":23682,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/23672\/revisions\/23682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/23679"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=23672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=23672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=23672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}