{"id":30168,"date":"2022-03-01T07:44:03","date_gmt":"2022-03-01T07:44:03","guid":{"rendered":"http:\/\/latribunera.com\/apuntes\/?p=30168"},"modified":"2022-03-01T07:50:27","modified_gmt":"2022-03-01T07:50:27","slug":"gignac-se-compadece-de-rayados","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/03\/01\/gignac-se-compadece-de-rayados\/","title":{"rendered":"Gignac se compadece de los Rayados"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Por\nVenustiano Carranza<\/p>\n\n\n\n<p>Andre-Pierre\nGignac no se anda con rodeos, va de frente en cualquier tema y si le preguntan\ndel rival no tiene recaudos en decir que no le gusta verlos en un mal momento futbol\u00edstico,\ninclusive le mand\u00f3 un mensaje de apoyo a Rogelio Funes Mori, quien no vive sus\nmejores \u00e9pocas en el club rayado.<\/p>\n\n\n\n<p><strong>\u00a1Esto dijo el franc\u00e9s en la \u00daltima Palabra de Fox Sports!<\/strong><\/p>\n\n\n\n<p><strong>\u00bfTe gusta que al rival le salgan mal las cosas?<\/strong><\/p>\n\n\n\n<p>\u201cA m\u00ed me gustar\u00eda\nver a mi rival a la par, me gustar\u00eda pelear porque tambi\u00e9n es el orgullo del\nNorte, me hubiera gustado que hicieran un buen Mundial, me hubiera dolido un\npoco que llegaran a la Final, pero ahora necesitan mucha tranquilidad, si\nopinan cambiar de entrenador es lo que est\u00e1n haciendo, pero la verdad los\nquiero fuerte, para que los Cl\u00e1sicos se ponga buenos, que haya algo m\u00e1s, un\nlugar entre los cuatro, un liderato, una Liguilla, y los quiero fuerte\u201d<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>\u00bfUna Final Regia?<\/strong><\/p>\n\n\n\n<p>&nbsp;\u201cSeria incre\u00edble, yo firmo ahorita para tener\nuna Final Regia, la verdad que me da un poco de tristeza por lo que est\u00e1n pasando\nlos jugadores, tengo contacto a veces con Funes Mori y me duele que un goleador\nhist\u00f3rico, con lo que le ha dado al club\u2026 hay rachas y para los delanteros m\u00e1s,\nlo que ha dado: super\u00f3 a uno de los mejores futbolistas que ha llegado a\nM\u00e9xico, que es Chupete Suazo, yo he visto videos y era un marciano el se\u00f1or, creaba,\ndaba pelotas, met\u00eda gol, pero me est\u00e1 doliendo que &nbsp;le pegan tanto a Funes Mori y no es para\nhacerme el humilde o algo as\u00ed, pero yo lo apoyo, le mand\u00e9 mensaje porque se\nmerece mucho m\u00e1s\u201d<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 opinas del comportamiento de la afici\u00f3n rayada hacia sus\nfutbolistas?<\/strong><\/p>\n\n\n\n<p>\u201cCada quien\nvive su pasi\u00f3n, pero no es mi lugar hablar de la afici\u00f3n del equipo rival, sabemos\nde la rivalidad, a m\u00ed me pegaron mucho y es parte del show; no hay problema, al\ncontrario, a m\u00ed me hace avanzar, me hace m\u00e1s fuerte, me gusta, entre comillas,\ncallar bocas.<\/p>\n\n\n\n<p>\u201cYo no creo\nque los jugadores quieran perder, ni que tiren la toalla para correr al t\u00e9cnico,\nnunca lo he visto en el futbol, es imposible porque es no amor a su deporte,\npero cada quien vive su pasi\u00f3n como lo entiende, yo creo que es un momento dif\u00edcil\npara ellos y que van a salir de esta y que har\u00e1n torneos protagonistas como\nsiempre lo hicieron en torneos pasados\u201d<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/bit.ly\/3C1BNAS\">\u00bfRAYADOS O AM\u00c9RICA?; LA PREGUNTA INC\u00d3MODA A GIGNAC<\/a><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Erika Gadea | Solo Tigres #18 | Entrevista\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/EQxZVJxbsE8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Venustiano Carranza Andre-Pierre Gignac no se anda con rodeos, va de frente en cualquier tema y si le preguntan del rival no tiene recaudos en decir que no le gusta verlos en un mal momento futbol\u00edstico, inclusive le mand\u00f3 un mensaje de apoyo a Rogelio Funes Mori, quien no vive sus mejores \u00e9pocas en&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/03\/01\/gignac-se-compadece-de-rayados\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":7,"featured_media":30172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[231,278],"tags":[299,74,6,102],"class_list":["post-30168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apuntes","category-solotigres","tag-gignac","tag-liga-mx","tag-rayados","tag-tigres"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2022\/03\/Dise\u00f1o-sin-t\u00edtulo-1.jpg","jetpack-related-posts":[{"id":45392,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/09\/se-presento-la-13va-edicion-del-guerreton\/","url_meta":{"origin":30168,"position":0},"title":"Se presento la 13va edici\u00f3n del Guerret\u00f3n.","author":"Staff","date":"9 abril, 2026","format":false,"excerpt":"A lo largo de sus primeras 12 ediciones, Guerret\u00f3n ha logrado recolectar m\u00e1s de 121,500juguetes, peluches y balones, beneficiando a diversas asociaciones e instituciones de laregi\u00f3n lagunera, entre ellas CRIT Durango, los sistemas DIF de distintos municipios, as\u00edcomo organizaciones educativas y asistenciales. A la fecha, se han instalado cuatro ludotecas\u2026","rel":"","context":"In &quot;Ganar Sirviendo&quot;","block_context":{"text":"Ganar Sirviendo","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/futbol\/futbol-mexicano\/ganar-sirviendo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/30168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=30168"}],"version-history":[{"count":5,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/30168\/revisions"}],"predecessor-version":[{"id":30174,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/30168\/revisions\/30174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/30172"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=30168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=30168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=30168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}