{"id":32697,"date":"2022-04-08T03:04:06","date_gmt":"2022-04-08T03:04:06","guid":{"rendered":"http:\/\/latribunera.com\/apuntes\/?p=32697"},"modified":"2022-04-08T20:02:37","modified_gmt":"2022-04-08T20:02:37","slug":"los-cambios-no-funcionaron","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/04\/08\/los-cambios-no-funcionaron\/","title":{"rendered":"LOS CAMBIOS NO FUNCIONARON"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Por: Ren\u00e9\nFern\u00e1ndez | Twitter: @Renefdz<\/p>\n\n\n\n<p>El t\u00e9cnico\nde Tigres, Miguel Herrera, reconoci\u00f3 que los cambios que realiz\u00f3 en el partido\nante Pachuca no resultaron como lo esperaba. <\/p>\n\n\n\n<p>&#8220;No,\nQui\u00f1ones hace un buen partido, no quer\u00eda sacarlo porque estaba pesando por el\nlado izquierdo, cuando hacemos el cambio de Charly fue en su momento, con Guido\nsale para darle movilidad en media cancha, por eso puse a un joven con m\u00e1s\nfrescura, ah\u00ed nos perdemos por querer apretar m\u00e1s arriba, nos ganan en ese\nespacio pero vamos a tratar de hacer la idea conforme vamos viendo a los\njugadores, Flo gambeteando y tirando centros, pero reitero, tuvimos\noportunidades y no la pudimos meter&#8221;, declar\u00f3. <\/p>\n\n\n\n<p>El equipo\nfelino tendr\u00e1 muy r\u00e1pido su revancha deportiva pues ya el pr\u00f3ximo domingo se\nenfrentar\u00e1n al Quer\u00e9taro en partido de la fecha 13.<\/p>\n\n\n\n<p>\u201cDame tiempo, iremos con la idea de ganar, no funcion\u00f3 el resultado, pero salimos con esa idea y cuando salimos as\u00ed estar\u00e1 m\u00e1s cerca el objetivo\u201d, finaliz\u00f3.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<figure class=\"wp-block-embed-spotify wp-block-embed is-type-rich is-provider-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Spotify Embed: Gabriel \u2018La Coca\u2019 Mendoza. Solo Tigres #24\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" src=\"https:\/\/open.spotify.com\/embed\/episode\/0Ysw0vPWWrIFH47UVsTuVd?si=ZAyAsMnNTvS6qwK0hd7Utw&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Gabriel \u2018La Coca\u2019 Mendoza | Solo Tigres #24 | Entrevista\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/t2AqfuUknhc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por: Ren\u00e9 Fern\u00e1ndez | Twitter: @Renefdz El t\u00e9cnico de Tigres, Miguel Herrera, reconoci\u00f3 que los cambios que realiz\u00f3 en el partido ante Pachuca no resultaron como lo esperaba. &#8220;No, Qui\u00f1ones hace un buen partido, no quer\u00eda sacarlo porque estaba pesando por el lado izquierdo, cuando hacemos el cambio de Charly fue en su momento, con&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/04\/08\/los-cambios-no-funcionaron\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":57,"featured_media":32698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[231,278],"tags":[74,102],"class_list":["post-32697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apuntes","category-solotigres","tag-liga-mx","tag-tigres"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2022\/04\/Dise\u00f1o-sin-t\u00edtulo-3-2.jpg","jetpack-related-posts":[{"id":45386,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/03\/11\/santos-launa-impulsa-mejoras-en-la-infraestructura-de-tsm-y-estadio-corona\/","url_meta":{"origin":32697,"position":0},"title":"Santos Laguna impulsa mejoras en la infraestructura de TSM y Estadio Corona","author":"Jacob Alarcon","date":"11 marzo, 2026","format":false,"excerpt":"Club Santos Laguna lleva a cabo una serie de reformas y mejoras en la infraestructura de TerritorioSantos Modelo y del Estadio Corona, con el objetivo de impulsar la innovaci\u00f3n tecnol\u00f3gica, lasostenibilidad y la modernizaci\u00f3n de sus espacios.Con estas acciones, el club contin\u00faa fortaleciendo la experiencia de sus aficionados yactualizando sus\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45392,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/09\/se-presento-la-13va-edicion-del-guerreton\/","url_meta":{"origin":32697,"position":1},"title":"Se presento la 13va edici\u00f3n del Guerret\u00f3n.","author":"Staff","date":"9 abril, 2026","format":false,"excerpt":"A lo largo de sus primeras 12 ediciones, Guerret\u00f3n ha logrado recolectar m\u00e1s de 121,500juguetes, peluches y balones, beneficiando a diversas asociaciones e instituciones de laregi\u00f3n lagunera, entre ellas CRIT Durango, los sistemas DIF de distintos municipios, as\u00edcomo organizaciones educativas y asistenciales. A la fecha, se han instalado cuatro ludotecas\u2026","rel":"","context":"In &quot;Ganar Sirviendo&quot;","block_context":{"text":"Ganar Sirviendo","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/futbol\/futbol-mexicano\/ganar-sirviendo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45421,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/16\/todo-listo-para-la-14va-edicion-de-la-copa-internacional-santos-penoles\/","url_meta":{"origin":32697,"position":2},"title":"Todo listo para la 14va edici\u00f3n de la Copa Internacional Santos Pe\u00f1oles","author":"Jacob Alarcon","date":"16 abril, 2026","format":false,"excerpt":"Este jueves, en el Auditorio Orlegi de Territorio Santos Modelo, se llev\u00f3 a cabo la presentaci\u00f3noficial de la edici\u00f3n 2026 de la Copa Internacional Santos Pe\u00f1oles, torneo que se ha consolidadocomo uno de los m\u00e1s importantes a nivel infantil y juvenil en M\u00e9xico. Adem\u00e1s de brindar una competencia deportiva de\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/32697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=32697"}],"version-history":[{"count":4,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/32697\/revisions"}],"predecessor-version":[{"id":32728,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/32697\/revisions\/32728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/32698"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=32697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=32697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=32697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}