{"id":33938,"date":"2022-05-02T15:45:02","date_gmt":"2022-05-02T15:45:02","guid":{"rendered":"http:\/\/latribunera.com\/apuntes\/?p=33938"},"modified":"2022-05-02T15:45:03","modified_gmt":"2022-05-02T15:45:03","slug":"el-diente-felicito-a-gignac","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/05\/02\/el-diente-felicito-a-gignac\/","title":{"rendered":"EL DIENTE FELICIT\u00d3 A GIGNAC"},"content":{"rendered":"<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\n     style=\"display:inline-block;width:728px;height:90px\"\n     data-ad-client=\"ca-pub-9427576701762839\"\n     data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p>Por: Ren\u00e9 Fern\u00e1ndez I Twitter: @Renefdz<\/p>\n\n\n\n<p>Sin envidias y de goleador a goleador.<\/p>\n\n\n\n<p>Nico L\u00f3pez felicit\u00f3 a su compa\u00f1ero de equipo Andr\u00e9 Pierre Gignac por haber obtenido el t\u00edtulo de goleo del Clausura 2022.<\/p>\n\n\n\n<p>El delantero charr\u00faa de Tigres posteo una fotograf\u00eda en su cuenta de Instagram con la leyenda \u201cFelicidades goleador\u201d en la cual aparece abrazando y besando al atacante franc\u00e9s.<\/p>\n\n\n\n<p>El \u201cDiente\u201d, campe\u00f3n de goleo en el Apertura 2021 se reencontr\u00f3 con el gol en la pasada fecha 17 ante el Atlas, fue apenas el segundo en su cuenta en lo que va de la campa\u00f1a y ahora buscar\u00e1 seguir marcando en la pr\u00f3xima liguilla.<\/p>\n\n\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\"\n     style=\"display:inline-block;width:728px;height:90px\"\n     data-ad-client=\"ca-pub-9427576701762839\"\n     data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"&quot;Cuco&quot; Gonz\u00e1lez | Solo Tigres #27 | Entrevista\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/XK-gtW58VLs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-spotify wp-block-embed is-type-rich is-provider-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Spotify Embed: &quot;Cuco&quot; Gonz\u00e1lez. Solo Tigres #27\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" src=\"https:\/\/open.spotify.com\/embed\/episode\/5fjzYZm6mUvocG2CtUOt1G?si=f9z7TAupSTujkqeGkuaoAQ&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por: Ren\u00e9 Fern\u00e1ndez I Twitter: @Renefdz Sin envidias y de goleador a goleador. Nico L\u00f3pez felicit\u00f3 a su compa\u00f1ero de equipo Andr\u00e9 Pierre Gignac por haber obtenido el t\u00edtulo de goleo del Clausura 2022. El delantero charr\u00faa de Tigres posteo una fotograf\u00eda en su cuenta de Instagram con la leyenda \u201cFelicidades goleador\u201d en la cual&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/05\/02\/el-diente-felicito-a-gignac\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":57,"featured_media":33939,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,278],"tags":[74,326],"class_list":["post-33938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-mexicano","category-solotigres","tag-liga-mx","tag-solo-tigres"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2022\/05\/B438B418-CC14-4FB1-BB0D-E75EFA9BE524.jpeg","jetpack-related-posts":[{"id":45386,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/03\/11\/santos-launa-impulsa-mejoras-en-la-infraestructura-de-tsm-y-estadio-corona\/","url_meta":{"origin":33938,"position":0},"title":"Santos Laguna impulsa mejoras en la infraestructura de TSM y Estadio Corona","author":"Jacob Alarcon","date":"11 marzo, 2026","format":false,"excerpt":"Club Santos Laguna lleva a cabo una serie de reformas y mejoras en la infraestructura de TerritorioSantos Modelo y del Estadio Corona, con el objetivo de impulsar la innovaci\u00f3n tecnol\u00f3gica, lasostenibilidad y la modernizaci\u00f3n de sus espacios.Con estas acciones, el club contin\u00faa fortaleciendo la experiencia de sus aficionados yactualizando sus\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45421,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/16\/todo-listo-para-la-14va-edicion-de-la-copa-internacional-santos-penoles\/","url_meta":{"origin":33938,"position":1},"title":"Todo listo para la 14va edici\u00f3n de la Copa Internacional Santos Pe\u00f1oles","author":"Jacob Alarcon","date":"16 abril, 2026","format":false,"excerpt":"Este jueves, en el Auditorio Orlegi de Territorio Santos Modelo, se llev\u00f3 a cabo la presentaci\u00f3noficial de la edici\u00f3n 2026 de la Copa Internacional Santos Pe\u00f1oles, torneo que se ha consolidadocomo uno de los m\u00e1s importantes a nivel infantil y juvenil en M\u00e9xico. Adem\u00e1s de brindar una competencia deportiva de\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/33938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=33938"}],"version-history":[{"count":2,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/33938\/revisions"}],"predecessor-version":[{"id":33941,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/33938\/revisions\/33941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/33939"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=33938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=33938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=33938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}