{"id":34407,"date":"2022-05-14T03:28:40","date_gmt":"2022-05-14T03:28:40","guid":{"rendered":"http:\/\/latribunera.com\/apuntes\/?p=34407"},"modified":"2022-05-15T18:21:17","modified_gmt":"2022-05-15T18:21:17","slug":"amazonas-ponen-un-pie-en-la-gran-final","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/05\/14\/amazonas-ponen-un-pie-en-la-gran-final\/","title":{"rendered":"AMAZONAS PONEN UN PIE EN LA GRAN FINAL"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Por: Ren\u00e9 Fern\u00e1ndez | Twitter: @Renefdz<\/p>\n\n\n\n<p>Una nueva final se vislumbra en el horizonte de Tigres Femenil.<\/p>\n\n\n\n<p>Las amazonas vencieron 2-0 a las Chivas en el juego de ida de las semifinales y viajar\u00e1n con una buena ventaja para el partido de vuelta que se jugar\u00e1 el pr\u00f3ximo lunes en la Perla Tapat\u00eda.<\/p>\n\n\n\n<p>A pesar de buscarlo, las dirigidas por Roberto Medina no pudieron encontrar el gol durante el primer tiempo y fue hasta la parte complementaria que la recompensa lleg\u00f3 con un par de cabezazos letales, primero de Mia Fishel y posteriormente de Uchenna Kanu con los cuales sellaron el triunfo frente a las rojiblancas.<\/p>\n\n\n\n<p>Fue una noche muy tranquila para la arquera felina Cecilia Santiago que no fue exigida por el ataque de las Chivas.<\/p>\n\n\n\n<p>Tigres Femenil est\u00e1 a 90 minutos de una nueva final, veremos si el lunes son capaces de amarrar definitivamente ese boleto a la \u00faltima batalla por el t\u00edtulo del Clausura 2022.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"V\u00edctor Alvarado | Solo Tigres #28 | Entrevista\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/pB9gXSn0Hc4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-spotify wp-block-embed is-type-rich is-provider-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Spotify Embed: V\u00edctor Alvarado. Solo Tigres #28\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" src=\"https:\/\/open.spotify.com\/embed\/episode\/6kLLwsIayAsbe9a5NiDEgM?si=jMwYOYK6TmG5xAuwCdUDHw&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por: Ren\u00e9 Fern\u00e1ndez | Twitter: @Renefdz Una nueva final se vislumbra en el horizonte de Tigres Femenil. Las amazonas vencieron 2-0 a las Chivas en el juego de ida de las semifinales y viajar\u00e1n con una buena ventaja para el partido de vuelta que se jugar\u00e1 el pr\u00f3ximo lunes en la Perla Tapat\u00eda. A pesar&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/05\/14\/amazonas-ponen-un-pie-en-la-gran-final\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":57,"featured_media":34408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[231,278],"tags":[256,158],"class_list":["post-34407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apuntes","category-solotigres","tag-liga-mx-femenil","tag-tigres-femenil"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2022\/05\/Dise\u00f1o-sin-t\u00edtulo-15.jpg","jetpack-related-posts":[{"id":45421,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/16\/todo-listo-para-la-14va-edicion-de-la-copa-internacional-santos-penoles\/","url_meta":{"origin":34407,"position":0},"title":"Todo listo para la 14va edici\u00f3n de la Copa Internacional Santos Pe\u00f1oles","author":"Jacob Alarcon","date":"16 abril, 2026","format":false,"excerpt":"Este jueves, en el Auditorio Orlegi de Territorio Santos Modelo, se llev\u00f3 a cabo la presentaci\u00f3noficial de la edici\u00f3n 2026 de la Copa Internacional Santos Pe\u00f1oles, torneo que se ha consolidadocomo uno de los m\u00e1s importantes a nivel infantil y juvenil en M\u00e9xico. Adem\u00e1s de brindar una competencia deportiva de\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/34407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=34407"}],"version-history":[{"count":3,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/34407\/revisions"}],"predecessor-version":[{"id":34463,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/34407\/revisions\/34463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/34408"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=34407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=34407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=34407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}