{"id":35870,"date":"2022-06-30T03:17:57","date_gmt":"2022-06-30T03:17:57","guid":{"rendered":"http:\/\/latribunera.com\/apuntes\/?p=35870"},"modified":"2022-06-30T16:31:27","modified_gmt":"2022-06-30T16:31:27","slug":"luis-quinones-titular-o-suplente-vs-cruz-azul","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/06\/30\/luis-quinones-titular-o-suplente-vs-cruz-azul\/","title":{"rendered":"Luis Qui\u00f1ones \u00bfTitular o suplente vs Cruz Azul?"},"content":{"rendered":"<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><strong>STAFF <\/strong><\/p>\n\n\n\n<p>Luis Qui\u00f1ones se reintegr\u00f3 a los entrenamientos de Tigres pero no estar\u00eda siendo considerado como titular para el partido de este s\u00e1bado ante Cruz Azul. <\/p>\n\n\n\n<p>Trascendi\u00f3 que el colombiano no form\u00f3 parte del cuadro estelar en el primer ensayo futbol\u00edstico que orden\u00f3 el t\u00e9cnico Miguel Herrera de cara al debut de su equipo en el Apertura 2022. <\/p>\n\n\n\n<p>El plantel entren\u00f3 a las 18:00 horas en la cancha del Estadio Universitario y ah\u00ed el \u201cPiojo\u201d par\u00f3 el que pinta para ser el 11 titular frente a la m\u00e1quina el cual estuvo conformado por Miguel Ortega en el arco, Jes\u00fas Angulo como carrilero izquierdo, Diego Reyes e Igor Lichnovsky en la central y Javier Aquino como carrilero por derecha.  <\/p>\n\n\n\n<p>Guido Pizarro y Juan Pablo Vig\u00f3n en la contenci\u00f3n con Sebasti\u00e1n C\u00f3rdova de enganche. Yeferson Soteldo actu\u00f3 como volante por izquierda y Florian por derecha, Andr\u00e9 Pierre Gignac en el centro del ataque. <\/p>\n\n\n\n<p>El equipo suplente gan\u00f3 2-1 con anotaciones del \u201cDiente\u201d L\u00f3pez mientras que por los titulares descont\u00f3 Juan Pablo Vig\u00f3n. <\/p>\n\n\n\n<p>Este jueves Miguel Herrera realizar\u00e1 un \u00faltimo interescuadras de cara al partido ante Cruz Azul.<\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Carlos Turrubiates. Solo Tigres #35 | Entrevista\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/EpWCpdgyUgs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-spotify wp-block-embed is-type-rich is-provider-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Spotify Embed: Carlos Turrubiates. Solo Tigres #35\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" src=\"https:\/\/open.spotify.com\/embed\/episode\/6xFnVs6ZYyUBZceRv0YjEY?utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>STAFF Luis Qui\u00f1ones se reintegr\u00f3 a los entrenamientos de Tigres pero no estar\u00eda siendo considerado como titular para el partido de este s\u00e1bado ante Cruz Azul. Trascendi\u00f3 que el colombiano no form\u00f3 parte del cuadro estelar en el primer ensayo futbol\u00edstico que orden\u00f3 el t\u00e9cnico Miguel Herrera de cara al debut de su equipo en&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/06\/30\/luis-quinones-titular-o-suplente-vs-cruz-azul\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":22,"featured_media":35871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[278],"tags":[686,508,389,298],"class_list":["post-35870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solotigres","tag-liga-bbva-mx","tag-luis-quinones","tag-miguel-herrera","tag-tigres-uanl"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-29-at-9.00.45-PM.jpeg","jetpack-related-posts":[{"id":45386,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/03\/11\/santos-launa-impulsa-mejoras-en-la-infraestructura-de-tsm-y-estadio-corona\/","url_meta":{"origin":35870,"position":0},"title":"Santos Laguna impulsa mejoras en la infraestructura de TSM y Estadio Corona","author":"Jacob Alarcon","date":"11 marzo, 2026","format":false,"excerpt":"Club Santos Laguna lleva a cabo una serie de reformas y mejoras en la infraestructura de TerritorioSantos Modelo y del Estadio Corona, con el objetivo de impulsar la innovaci\u00f3n tecnol\u00f3gica, lasostenibilidad y la modernizaci\u00f3n de sus espacios.Con estas acciones, el club contin\u00faa fortaleciendo la experiencia de sus aficionados yactualizando sus\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45392,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/09\/se-presento-la-13va-edicion-del-guerreton\/","url_meta":{"origin":35870,"position":1},"title":"Se presento la 13va edici\u00f3n del Guerret\u00f3n.","author":"Staff","date":"9 abril, 2026","format":false,"excerpt":"A lo largo de sus primeras 12 ediciones, Guerret\u00f3n ha logrado recolectar m\u00e1s de 121,500juguetes, peluches y balones, beneficiando a diversas asociaciones e instituciones de laregi\u00f3n lagunera, entre ellas CRIT Durango, los sistemas DIF de distintos municipios, as\u00edcomo organizaciones educativas y asistenciales. A la fecha, se han instalado cuatro ludotecas\u2026","rel":"","context":"In &quot;Ganar Sirviendo&quot;","block_context":{"text":"Ganar Sirviendo","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/futbol\/futbol-mexicano\/ganar-sirviendo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/9Guerreton-2026-2.jpg.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45421,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/16\/todo-listo-para-la-14va-edicion-de-la-copa-internacional-santos-penoles\/","url_meta":{"origin":35870,"position":2},"title":"Todo listo para la 14va edici\u00f3n de la Copa Internacional Santos Pe\u00f1oles","author":"Jacob Alarcon","date":"16 abril, 2026","format":false,"excerpt":"Este jueves, en el Auditorio Orlegi de Territorio Santos Modelo, se llev\u00f3 a cabo la presentaci\u00f3noficial de la edici\u00f3n 2026 de la Copa Internacional Santos Pe\u00f1oles, torneo que se ha consolidadocomo uno de los m\u00e1s importantes a nivel infantil y juvenil en M\u00e9xico. Adem\u00e1s de brindar una competencia deportiva de\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/35870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=35870"}],"version-history":[{"count":3,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/35870\/revisions"}],"predecessor-version":[{"id":35883,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/35870\/revisions\/35883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/35871"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=35870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=35870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=35870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}