{"id":37129,"date":"2022-08-17T17:23:29","date_gmt":"2022-08-17T17:23:29","guid":{"rendered":"http:\/\/latribunera.com\/apuntes\/?p=37129"},"modified":"2022-08-17T17:23:31","modified_gmt":"2022-08-17T17:23:31","slug":"el-piojo-realizo-primer-ensayo-rumbo-al-clasico","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/08\/17\/el-piojo-realizo-primer-ensayo-rumbo-al-clasico\/","title":{"rendered":"EL \u201cPIOJO\u201d REALIZ\u00d3 PRIMER ENSAYO RUMBO AL CL\u00c1SICO"},"content":{"rendered":"\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p>Por: Ren\u00e9 Fern\u00e1ndez I Twitter: @Renefdz<\/p>\n\n\n\n<p>El t\u00e9cnico de Tigres, Miguel Herrera, comenz\u00f3 a pulir el 11 titular que podr\u00eda utilizar en el pr\u00f3ximo Cl\u00e1sico Regio 128.<\/p>\n\n\n\n<p>El equipo felino entren\u00f3 en el Estadio Universitario y durante el primer interescuadras de la semana el \u201cPiojo\u201d par\u00f3 el siguiente cuadro: <\/p>\n\n\n\n<p>Nahuel Guzm\u00e1n, l\u00ednea de tres centrales con Jes\u00fas Angulo, Igor Lichnovsky y Diego Reyes. <\/p>\n\n\n\n<p>Vladimir Loro\u00f1a estuvo como lateral por derecha y Francisco Venegas por izquierda en lugar de Javier Aquino quien sigue trabajando por separado a causa de un golpe en el pie derecho. <\/p>\n\n\n\n<p>En la media de contenci\u00f3n jugaron Guido Pizarro y Sebasti\u00e1n C\u00f3rdova con Luis Qui\u00f1ones como extremo por izquierda, Nico L\u00f3pez por derecha y Andr\u00e9 Pierre Gignac en punta.<\/p>\n\n\n\n<p>Ma\u00f1ana jueves se espera que Miguel Herrera vuelva a realizar trabajo de f\u00fatbol y decida con cu\u00e1l alineaci\u00f3n afrontar\u00e1 de inicio el partido ante Rayados.<\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00d3scar S\u00e1nchez. Solo Tigres #41 | Entrevista\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/HMiqDsRHUCc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por: Ren\u00e9 Fern\u00e1ndez I Twitter: @Renefdz El t\u00e9cnico de Tigres, Miguel Herrera, comenz\u00f3 a pulir el 11 titular que podr\u00eda utilizar en el pr\u00f3ximo Cl\u00e1sico Regio 128. El equipo felino entren\u00f3 en el Estadio Universitario y durante el primer interescuadras de la semana el \u201cPiojo\u201d par\u00f3 el siguiente cuadro: Nahuel Guzm\u00e1n, l\u00ednea de tres centrales&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/08\/17\/el-piojo-realizo-primer-ensayo-rumbo-al-clasico\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":57,"featured_media":37130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,278],"tags":[74,326],"class_list":["post-37129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-mexicano","category-solotigres","tag-liga-mx","tag-solo-tigres"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2022\/08\/Picsart_22-08-17_12-16-19-995.jpg","jetpack-related-posts":[{"id":45386,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/03\/11\/santos-launa-impulsa-mejoras-en-la-infraestructura-de-tsm-y-estadio-corona\/","url_meta":{"origin":37129,"position":0},"title":"Santos Laguna impulsa mejoras en la infraestructura de TSM y Estadio Corona","author":"Jacob Alarcon","date":"11 marzo, 2026","format":false,"excerpt":"Club Santos Laguna lleva a cabo una serie de reformas y mejoras en la infraestructura de TerritorioSantos Modelo y del Estadio Corona, con el objetivo de impulsar la innovaci\u00f3n tecnol\u00f3gica, lasostenibilidad y la modernizaci\u00f3n de sus espacios.Con estas acciones, el club contin\u00faa fortaleciendo la experiencia de sus aficionados yactualizando sus\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45421,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/16\/todo-listo-para-la-14va-edicion-de-la-copa-internacional-santos-penoles\/","url_meta":{"origin":37129,"position":1},"title":"Todo listo para la 14va edici\u00f3n de la Copa Internacional Santos Pe\u00f1oles","author":"Jacob Alarcon","date":"16 abril, 2026","format":false,"excerpt":"Este jueves, en el Auditorio Orlegi de Territorio Santos Modelo, se llev\u00f3 a cabo la presentaci\u00f3noficial de la edici\u00f3n 2026 de la Copa Internacional Santos Pe\u00f1oles, torneo que se ha consolidadocomo uno de los m\u00e1s importantes a nivel infantil y juvenil en M\u00e9xico. Adem\u00e1s de brindar una competencia deportiva de\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/37129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=37129"}],"version-history":[{"count":2,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/37129\/revisions"}],"predecessor-version":[{"id":37132,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/37129\/revisions\/37132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/37130"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=37129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=37129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=37129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}