{"id":38232,"date":"2022-10-10T18:27:56","date_gmt":"2022-10-10T18:27:56","guid":{"rendered":"http:\/\/latribunera.com\/apuntes\/?p=38232"},"modified":"2022-10-10T18:27:59","modified_gmt":"2022-10-10T18:27:59","slug":"aplausos-para-raymundo-fulgencio","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/10\/10\/aplausos-para-raymundo-fulgencio\/","title":{"rendered":"Aplausos para Raymundo Fulgencio"},"content":{"rendered":"\n<p>El s\u00e1bado 8 de octubre, en punto de las 19 horas, Tigres\ny Necaxa se enfrentaron por el repechaje en el \u2018Volc\u00e1n\u2019 Universitario, siendo\nlos dirigidos por Miguel: el \u2018Piojo\u2019 Herrera los ganadores.<\/p>\n\n\n\n<p>Ahora les toca medir fuerzas contra el Pachuca, en una\nllave bastante complicada.<\/p>\n\n\n\n<p>Sin embargo, no quiero darle vuelta a la p\u00e1gina sin antes\ndedicarle unas palabras a un futbolista que, no solo dio un PARTIDAZO ante los\nRayos, sino que ha venido haciendo las cosas bien desde que arranc\u00f3 el torneo.<\/p>\n\n\n\n<p>Se llama Raymundo, se apellida Fulgencio y merece los\naplausos de todos nosotros.<\/p>\n\n\n\n<p>No es f\u00e1cil sumar minutos en un equipo plagado de figuras,\ncomo lo es Tigres.<\/p>\n\n\n\n<p>Menos si eres un extremo y te toca competir contra Luis\nQui\u00f1ones, por ejemplo, que aunque no tuvo un buen semestre y los aficionados no\nest\u00e1n del todo contentos con \u00e9l, calidad tiene, y de sobra. Adem\u00e1s de que\nMiguel Herrera le tiene una confianza ciega.<\/p>\n\n\n\n<p>Y el tema no para en ganarle la partida al colombiano.<\/p>\n\n\n\n<p>No.<\/p>\n\n\n\n<p>Nada de eso.<\/p>\n\n\n\n<p>Tambi\u00e9n tiene que competir contra Florian Thauvin, que\nlleg\u00f3 a Tigres con un cartel del tama\u00f1o del \u2018Volc\u00e1n\u2019, y con \u2018Diente\u2019 L\u00f3pez, que\nya sali\u00f3 campe\u00f3n de goleo bajo el mando del \u2018Piojo\u2019 Herrera y que se ha visto\nbien en los pocos minutos que ha tenido dentro del rect\u00e1ngulo verde.<\/p>\n\n\n\n<p>Lo del \u2018Rayo\u2019 merece todos nuestros reconocimientos,\nporque el chico se ha ido a la banca SIN MERECERLO, y a\u00fan as\u00ed, cuando entra,\nas\u00ed sean diez, quince, veinte o cuarenta minutos, suda hasta la \u00faltima gota y\nhace bien las cosas.<\/p>\n\n\n\n<p>Antes se le criticaba por no tener buen centro, pero el\ns\u00e1bado frente al Necaxa, Raymundo Fulgencio le puso una pelota precisa a Andr\u00e9-Pierre\nGignac, para el segundo tanto de la noche, demostrando que est\u00e1 trabajando en\nsus \u00e1reas de oportunidad y que quiere adue\u00f1arse de la titularidad.<\/p>\n\n\n\n<p>Por derecha o por izquierda; de extremo o hasta de lateral,\ncomo le toc\u00f3 jugar frente a los Rayos, tras la expulsi\u00f3n de Javier Aquino.<\/p>\n\n\n\n<p>\u2018Rayful\u2019 sigue cumpliendo, y cada vez se vuelve m\u00e1s\nimportante en el esquema de Miguel Herrera.<\/p>\n\n\n\n<p>\u00bfLo veremos de titular ante Pachuca?<\/p>\n\n\n\n<p>Yo creo que s\u00ed.<\/p>\n\n\n\n<p>Twitter:&nbsp;<strong><a href=\"http:\/\/www.twitter.com\/JaimeGarza94\">JaimeGarza94<\/a><\/strong><\/p>\n\n\n\n<p>Instagram:<a href=\"http:\/\/www.instagram.com\/JaimeGarzaEditorial\">&nbsp;<strong>JaimeGarzaEditorial<\/strong><\/a><\/p>\n\n\n\n<p>Tambi\u00e9n te puede interesar:&nbsp;<strong><a href=\"http:\/\/latribunera.com\/apuntes\/index.php\/2022\/08\/31\/el-verdadero-nivel-de-jordy-caicedo\/\">El verdadero nivel de Jordy Caicedo<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 8 de octubre, en punto de las 19 horas, Tigres y Necaxa se enfrentaron por el repechaje en el \u2018Volc\u00e1n\u2019 Universitario, siendo los dirigidos por Miguel: el \u2018Piojo\u2019 Herrera los ganadores. Ahora les toca medir fuerzas contra el Pachuca, en una llave bastante complicada. Sin embargo, no quiero darle vuelta a la p\u00e1gina&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2022\/10\/10\/aplausos-para-raymundo-fulgencio\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":23,"featured_media":36275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[278],"tags":[],"class_list":["post-38232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solotigres"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2022\/07\/fbl-mex-tigres-tijuana.jpg","jetpack-related-posts":[{"id":45386,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/03\/11\/santos-launa-impulsa-mejoras-en-la-infraestructura-de-tsm-y-estadio-corona\/","url_meta":{"origin":38232,"position":0},"title":"Santos Laguna impulsa mejoras en la infraestructura de TSM y Estadio Corona","author":"Jacob Alarcon","date":"11 marzo, 2026","format":false,"excerpt":"Club Santos Laguna lleva a cabo una serie de reformas y mejoras en la infraestructura de TerritorioSantos Modelo y del Estadio Corona, con el objetivo de impulsar la innovaci\u00f3n tecnol\u00f3gica, lasostenibilidad y la modernizaci\u00f3n de sus espacios.Con estas acciones, el club contin\u00faa fortaleciendo la experiencia de sus aficionados yactualizando sus\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45421,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/16\/todo-listo-para-la-14va-edicion-de-la-copa-internacional-santos-penoles\/","url_meta":{"origin":38232,"position":1},"title":"Todo listo para la 14va edici\u00f3n de la Copa Internacional Santos Pe\u00f1oles","author":"Jacob Alarcon","date":"16 abril, 2026","format":false,"excerpt":"Este jueves, en el Auditorio Orlegi de Territorio Santos Modelo, se llev\u00f3 a cabo la presentaci\u00f3noficial de la edici\u00f3n 2026 de la Copa Internacional Santos Pe\u00f1oles, torneo que se ha consolidadocomo uno de los m\u00e1s importantes a nivel infantil y juvenil en M\u00e9xico. Adem\u00e1s de brindar una competencia deportiva de\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/38232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=38232"}],"version-history":[{"count":3,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/38232\/revisions"}],"predecessor-version":[{"id":38235,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/38232\/revisions\/38235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/36275"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=38232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=38232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=38232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}