{"id":40608,"date":"2023-02-16T22:19:23","date_gmt":"2023-02-16T22:19:23","guid":{"rendered":"http:\/\/latribunera.com\/apuntes\/?p=40608"},"modified":"2023-02-16T22:19:26","modified_gmt":"2023-02-16T22:19:26","slug":"tigres-y-rayados-candidatos-al-titulo-vigon","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2023\/02\/16\/tigres-y-rayados-candidatos-al-titulo-vigon\/","title":{"rendered":"TIGRES Y RAYADOS CANDIDATOS AL T\u00cdTULO: VIG\u00d3N"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Por: Ren\u00e9 Fern\u00e1ndez | Twitter: @Renefdz <\/p>\n\n\n\n<p>En las \u00faltimas semanas mucho se ha criticado a los equipos regios, especialmente a Tigres, por la inversi\u00f3n en refuerzos realizada para el Torneo de Clausura 2023, la cual para su jugador, Juan Pablo Vig\u00f3n, ha valido la pena.  <\/p>\n\n\n\n<p>El futbolista felino no solamente habl\u00f3 de su instituci\u00f3n, tambi\u00e9n lo hizo del rival de la ciudad y afirm\u00f3 que ambos ser\u00e1n serios contendientes para ganar el actual campeonato.  <\/p>\n\n\n\n<p>\u201cFeliz, me siento orgulloso, con mucho honor de pertenecer a esta instituci\u00f3n, los dos equipos de ac\u00e1 del norte estamos peleando los primeros resultados, creo que la inversi\u00f3n ah\u00ed se ve reflejada y creo que vamos a ser de los candidatos al t\u00edtulo\u201d, declar\u00f3. <\/p>\n\n\n\n<p>Vig\u00f3n se encuentra disputando su quinto torneo con la piel felina y aunque su participaci\u00f3n ha venido a menos, no ocult\u00f3 su alegr\u00eda por pertenecer a un equipo como Tigres. <\/p>\n\n\n\n<p>\u201cMe siento muy contento de estar ac\u00e1, ya es mucho rato que se habla de Tigres, de Monterrey, es que algo est\u00e1n haciendo bien, me siento feliz de pertenecer y con muchas ganas de seguir haciendo lo que Tigres ha hecho que ha trascendido el f\u00fatbol mexicano\u201d, finaliz\u00f3.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Jos\u00e9 Francisco \u201cGringo\u201d Torres. SoloTigres #59 | \u00bfPorqu\u00e9 no jugu\u00e9 mucho en Tigres?\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/vv2C-QgwM_A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- PC 728x90 --><br \/>\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:728px;height:90px\" data-ad-client=\"ca-pub-9427576701762839\" data-ad-slot=\"1011393878\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Ren\u00e9 Fern\u00e1ndez | Twitter: @Renefdz En las \u00faltimas semanas mucho se ha criticado a los equipos regios, especialmente a Tigres, por la inversi\u00f3n en refuerzos realizada para el Torneo de Clausura 2023, la cual para su jugador, Juan Pablo Vig\u00f3n, ha valido la pena. El futbolista felino no solamente habl\u00f3 de su instituci\u00f3n, tambi\u00e9n&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2023\/02\/16\/tigres-y-rayados-candidatos-al-titulo-vigon\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":57,"featured_media":40623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[231,278],"tags":[],"class_list":["post-40608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apuntes","category-solotigres"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2023\/02\/Dise\u00f1o-sin-t\u00edtulo-14-1.jpg","jetpack-related-posts":[{"id":45478,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/08\/11\/club-santos-laguna-ofrece-a-su-aficion-el-pack-vs-chivas-tigres\/","url_meta":{"origin":40608,"position":0},"title":"Club Santos Laguna ofrece a su afici\u00f3n el pack vs Chivas + Tigres","author":"Staff","date":"11 agosto, 2026","format":false,"excerpt":"\u2022 El paquete asegura dos de los tres partidos de mayor demanda del semestre y da acceso preferente a la venta ante Tigres. Club Santos Laguna ofrece a su afici\u00f3n el Pack Santos vs Chivas + Tigres, un paquete especial que permite asegurar el lugar en dos de los duelos\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260810-WA0178.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260810-WA0178.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260810-WA0178.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260810-WA0178.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260810-WA0178.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260810-WA0178.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45502,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/08\/25\/el-corona-se-prepara-para-una-noche-especial-ante-tigres\/","url_meta":{"origin":40608,"position":1},"title":"El Corona se prepara para una noche especial ante Tigres","author":"Staff","date":"25 agosto, 2026","format":false,"excerpt":"Un nuevo duelo en el Estadio Corona est\u00e1 cada vez m\u00e1s cerca y la afici\u00f3n santista se prepara para vivir una noche llena de emociones. Los Guerreros recibir\u00e1n a Tigres este s\u00e1bado 29 de agosto a las 21:10 horas, en partido correspondiente a la jornada 6 del Torneo Apertura 2026.\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Drones-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Drones-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Drones-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Drones-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Drones-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Drones-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45489,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/08\/14\/santos-laguna-invita-a-su-aficion-a-pintar-de-verde-el-corona-ante-chivas\/","url_meta":{"origin":40608,"position":2},"title":"Santos Laguna invita a su afici\u00f3n a pintar de verde el Corona ante Chivas.","author":"Staff","date":"14 agosto, 2026","format":false,"excerpt":"\u2022 Los Guerreros regresan a casa con el envi\u00f3n an\u00edmico de su triunfo ante Philadelphia Union y buscar\u00e1n, junto a su afici\u00f3n, su primera victoria del Apertura 2026. Luego de cerrar su participaci\u00f3n en la Leagues Cup 2026 con una victoria de 2 a 0 sobre Philadelphia Union en el\u2026","rel":"","context":"In &quot;Liga MX&quot;","block_context":{"text":"Liga MX","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/futbol\/futbol-mexicano\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260814-WA0041.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260814-WA0041.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260814-WA0041.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260814-WA0041.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260814-WA0041.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/IMG-20260814-WA0041.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45513,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/08\/26\/exguerreros-mandan-mensajes-de-apoyo-a-santos-laguna\/","url_meta":{"origin":40608,"position":3},"title":"Exguerreros mandan mensajes de apoyo a Santos Laguna","author":"Staff","date":"26 agosto, 2026","format":false,"excerpt":"Exjugadores santistas comenzaron a manifestar su apoyo al Club Santos Laguna a trav\u00e9s de sus redes sociales, destacando la participaci\u00f3n de futbolistas de diferentes etapas en la historia de la instituci\u00f3n, recordados con mucho cari\u00f1o por la afici\u00f3n Guerrera y varios de ellos campeones con Santos Laguna. Entre quienes han\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Redes-Ex-Guerreros.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Redes-Ex-Guerreros.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Redes-Ex-Guerreros.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Redes-Ex-Guerreros.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Redes-Ex-Guerreros.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/08\/Redes-Ex-Guerreros.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45455,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/07\/20\/club-santos-laguna-impulsa-el-futuro-de-la-laguna-con-inversion-en-infraestructura\/","url_meta":{"origin":40608,"position":4},"title":"Club Santos Laguna impulsa el futuro de la laguna con inversi\u00f3n en infraestructura","author":"Staff","date":"20 julio, 2026","format":false,"excerpt":"En los \u00faltimos ocho meses, el Club ha destinado 75 millones de pesos a la modernizaci\u00f3n de Territorio Santos Modelo y el Estadio Corona. Los proyectos fortalecen la experiencia de aficionados, jugadores, colaboradores y socios comerciales, adem\u00e1s de generar un importante impacto econ\u00f3mico en la regi\u00f3n. Club Santos Laguna contin\u00faa\u2026","rel":"","context":"In &quot;Liga MX&quot;","block_context":{"text":"Liga MX","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/futbol\/futbol-mexicano\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/e60fc472-db6f-4c99-80aa-c65e7754feb1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/e60fc472-db6f-4c99-80aa-c65e7754feb1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/e60fc472-db6f-4c99-80aa-c65e7754feb1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/e60fc472-db6f-4c99-80aa-c65e7754feb1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/e60fc472-db6f-4c99-80aa-c65e7754feb1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/07\/e60fc472-db6f-4c99-80aa-c65e7754feb1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45386,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/03\/11\/santos-launa-impulsa-mejoras-en-la-infraestructura-de-tsm-y-estadio-corona\/","url_meta":{"origin":40608,"position":5},"title":"Santos Laguna impulsa mejoras en la infraestructura de TSM y Estadio Corona","author":"Jacob Alarcon","date":"11 marzo, 2026","format":false,"excerpt":"Club Santos Laguna lleva a cabo una serie de reformas y mejoras en la infraestructura de TerritorioSantos Modelo y del Estadio Corona, con el objetivo de impulsar la innovaci\u00f3n tecnol\u00f3gica, lasostenibilidad y la modernizaci\u00f3n de sus espacios.Con estas acciones, el club contin\u00faa fortaleciendo la experiencia de sus aficionados yactualizando sus\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/40608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=40608"}],"version-history":[{"count":3,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/40608\/revisions"}],"predecessor-version":[{"id":40625,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/40608\/revisions\/40625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/40623"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=40608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=40608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=40608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}