{"id":41380,"date":"2023-03-16T14:57:20","date_gmt":"2023-03-16T14:57:20","guid":{"rendered":"http:\/\/latribunera.com\/apuntes\/?p=41380"},"modified":"2023-03-16T14:57:23","modified_gmt":"2023-03-16T14:57:23","slug":"tigres-paso-y-ya","status":"publish","type":"post","link":"https:\/\/latribunera.com\/apuntes\/index.php\/2023\/03\/16\/tigres-paso-y-ya\/","title":{"rendered":"Tigres pas\u00f3&#8230; Y YA"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Tigres avanz\u00f3 a los Cuartos de Final de la CONCACAF pidiendo la hora, con Samir Caetano expulsado y con el Orlando City reclam\u00e1ndole no s\u00e9 qu\u00e9 cosa al silbante.<\/strong><\/h2>\n\n\n\n<p>Definitivamente Tigres sufri\u00f3 m\u00e1s de lo esperado.<\/p>\n\n\n\n<p>Tanto en la ida como en la vuelta el equipo se cans\u00f3 de fallar, pero de nueva cuenta la contundencia priv\u00f3 a los dirigidos por Marco Antonio: el &#8216;Chima&#8217; Ru\u00edz de un triunfo redondo que mucha falta les hace para ganar confianza de cara al cierre de torneo.<\/p>\n\n\n\n<p><strong>Lo importante era avanzar<\/strong><\/p>\n\n\n\n<p>En estas instancias el pase a la siguiente fase no es negociable.<\/p>\n\n\n\n<p>Jugando bien o jugando mal, brindando espet\u00e1culo o teniendo como h\u00e9roe a Nahuel Guzm\u00e1n, Tigres deb\u00eda avanzar s\u00ed o s\u00ed.<\/p>\n\n\n\n<p>Y avanz\u00f3&#8230;<\/p>\n\n\n\n<p>\u00bfMerecidamente?<\/p>\n\n\n\n<p>Creo que s\u00ed.<\/p>\n\n\n\n<p><strong>No todo es culpa del &#8216;Chima&#8217;<\/strong><\/p>\n\n\n\n<p>En este espacio (sobre todo su servidor), se le ha exigido duro al actual t\u00e9cnico felino.<\/p>\n\n\n\n<p>\u00bfLos motivos?<\/p>\n\n\n\n<p>La falta de variantes en partidos cerrados, la terquedad de intentar con Gorriar\u00e1n por fuera, el excesivo respeto a jugadores que ya no est\u00e1n para arrancar como titular, entre otras cosas.<\/p>\n\n\n\n<p>Sin embargo, tampoco podemos quitarle responsabilidad a los jugadores.<\/p>\n\n\n\n<p>Tigres debi\u00f3 resolverlo todo desde el duelo de ida. Y en la vuelta tambi\u00e9n tuvieron algunas oportunidades para acabar con el rival y llegar al noventa con mayor tranquilidad.<\/p>\n\n\n\n<p><strong>El cl\u00e1sico y a trabajar<\/strong><\/p>\n\n\n\n<p>No hay tiempo para que el equipo se detenga a preguntarse c\u00f3mo fue que acab\u00f3 sufiendo tanto en una llave aparentemente sencilla.<\/p>\n\n\n\n<p>Dentro de un par de d\u00edas se jugar\u00e1 el cl\u00e1sico regio ante un Rayados al que parece estarle saliendo todo bien.<\/p>\n\n\n\n<p>El derbi tambi\u00e9n es un partido que se debe ganar s\u00ed o s\u00ed, m\u00e1s all\u00e1 de las formas.<\/p>\n\n\n\n<p>Despu\u00e9s vendr\u00e1 la fecha FIFA, y entonces s\u00ed Tigres tendr\u00e1 tiempo para cuestionarse que est\u00e1 haciendo mal y corregirlo, con la intenci\u00f3n de afianzarse en la parte alta de la tabla y encarar de mejor manera la CONCACAF.<\/p>\n\n\n\n<p>Twitter:&nbsp;<strong><a href=\"http:\/\/www.twitter.com\/JaimeGarza94\">JaimeGarza94<\/a><\/strong><\/p>\n\n\n\n<p>Instagram:<a href=\"http:\/\/www.instagram.com\/JaimeGarzaEditorial\">&nbsp;<strong>JaimeGarzaEditorial<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tigres avanz\u00f3 a los Cuartos de Final de la CONCACAF pidiendo la hora, con Samir Caetano expulsado y con el Orlando City reclam\u00e1ndole no s\u00e9 qu\u00e9 cosa al silbante. Definitivamente Tigres sufri\u00f3 m\u00e1s de lo esperado. Tanto en la ida como en la vuelta el equipo se cans\u00f3 de fallar, pero de nueva cuenta la&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/latribunera.com\/apuntes\/index.php\/2023\/03\/16\/tigres-paso-y-ya\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":23,"featured_media":41381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[278],"tags":[],"class_list":["post-41380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solotigres"],"jetpack_featured_media_url":"https:\/\/latribunera.com\/apuntes\/wp-content\/uploads\/2023\/03\/equipo.jpg","jetpack-related-posts":[{"id":45386,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/03\/11\/santos-launa-impulsa-mejoras-en-la-infraestructura-de-tsm-y-estadio-corona\/","url_meta":{"origin":41380,"position":0},"title":"Santos Laguna impulsa mejoras en la infraestructura de TSM y Estadio Corona","author":"Jacob Alarcon","date":"11 marzo, 2026","format":false,"excerpt":"Club Santos Laguna lleva a cabo una serie de reformas y mejoras en la infraestructura de TerritorioSantos Modelo y del Estadio Corona, con el objetivo de impulsar la innovaci\u00f3n tecnol\u00f3gica, lasostenibilidad y la modernizaci\u00f3n de sus espacios.Con estas acciones, el club contin\u00faa fortaleciendo la experiencia de sus aficionados yactualizando sus\u2026","rel":"","context":"In &quot;Pasi\u00f3n Guerrera&quot;","block_context":{"text":"Pasi\u00f3n Guerrera","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/tribus\/pasionguerrera\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/03\/Renovacion-TSM.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45421,"url":"https:\/\/latribunera.com\/apuntes\/index.php\/2026\/04\/16\/todo-listo-para-la-14va-edicion-de-la-copa-internacional-santos-penoles\/","url_meta":{"origin":41380,"position":1},"title":"Todo listo para la 14va edici\u00f3n de la Copa Internacional Santos Pe\u00f1oles","author":"Jacob Alarcon","date":"16 abril, 2026","format":false,"excerpt":"Este jueves, en el Auditorio Orlegi de Territorio Santos Modelo, se llev\u00f3 a cabo la presentaci\u00f3noficial de la edici\u00f3n 2026 de la Copa Internacional Santos Pe\u00f1oles, torneo que se ha consolidadocomo uno de los m\u00e1s importantes a nivel infantil y juvenil en M\u00e9xico. Adem\u00e1s de brindar una competencia deportiva de\u2026","rel":"","context":"In &quot;Sin categor\u00eda&quot;","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/latribunera.com\/apuntes\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/latribunera.com\/apuntes\/wp-content\/uploads\/2026\/04\/Presentacion-Copa-Santos-Penoles.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/41380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/comments?post=41380"}],"version-history":[{"count":3,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/41380\/revisions"}],"predecessor-version":[{"id":41384,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/posts\/41380\/revisions\/41384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media\/41381"}],"wp:attachment":[{"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/media?parent=41380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/categories?post=41380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latribunera.com\/apuntes\/index.php\/wp-json\/wp\/v2\/tags?post=41380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}